{"id":4076,"date":"2019-12-16T10:41:04","date_gmt":"2019-12-16T03:41:04","guid":{"rendered":"https:\/\/www.pbru.ac.th\/pbru\/?page_id=4076"},"modified":"2020-02-04T14:52:54","modified_gmt":"2020-02-04T07:52:54","slug":"president","status":"publish","type":"page","link":"https:\/\/www.pbru.ac.th\/pbru\/president","title":{"rendered":"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35"},"content":{"rendered":"<h1><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-7178 aligncenter\" src=\"https:\/\/www.pbru.ac.th\/pbru\/wp-content\/uploads\/2020\/02\/pic-07-250x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/><\/h1>\n<h1 style=\"text-align: center;\"><strong>\u0e1e\u0e25\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e2d\u0e01 \u0e0a\u0e25\u0e34\u0e15 \u0e1e\u0e38\u0e01\u0e1c\u0e32\u0e2a\u0e38\u0e02 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35<\/strong><\/h1>\n<h3>\u0e27\u0e31\u0e19 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e1b\u0e35\u0e40\u0e01\u0e34\u0e14 5 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2491 \u0e2d\u0e32\u0e22\u0e38 71 \u0e1b\u0e35<\/h3>\n<h2><strong>\u0e04\u0e38\u0e13\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/strong><br \/>\n&#8211; \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e17\u0e2b\u0e32\u0e23 \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 6<br \/>\n&#8211; \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e32\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 13<br \/>\n&#8211; \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e32\u0e22\u0e17\u0e2b\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1d\u0e39\u0e07 \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 40<br \/>\n&#8211; \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e2a\u0e19\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 27<br \/>\n&#8211; \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e17\u0e31\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 25<br \/>\n&#8211; \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 41<br \/>\n&#8211; \u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e04\u0e23\u0e39\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e44\u0e2d\u0e1e\u0e48\u0e19 (PILOT INSTRUCTOR T-38) \u0e42\u0e14\u0e22\u0e17\u0e38\u0e19 IMETP \u0e17\u0e35\u0e48\u0e0b\u0e32\u0e19\u0e2d\u0e31\u0e19\u0e42\u0e15\u0e19\u0e35\u0e42\u0e2d \u0e23\u0e31\u0e10\u0e40\u0e17\u0e01\u0e0b\u0e31\u0e2a \u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/h2>\n<h2><strong>\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19<\/strong><br \/>\n\u0e2d\u0e07\u0e04\u0e21\u0e19\u0e15\u0e23\u0e35 (\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 \u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f \u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2554 \/ \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 10 \u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f \u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2559)<\/h2>\n<h2><strong>\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15<\/strong><br \/>\n&#8211; \u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e2d\u0e32\u0e01\u0e32\u0e28<br \/>\n&#8211; \u0e23\u0e2d\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e13\u0e30\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e01\u0e32\u0e23\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e2d\u0e31\u0e19\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e29\u0e31\u0e15\u0e23\u0e34\u0e22\u0e4c\u0e17\u0e23\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e38\u0e02 (\u0e04\u0e1b\u0e04.) \u0e04\u0e19\u0e17\u0e35\u0e48 1<br \/>\n&#8211; \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2d\u0e32\u0e2a\u0e32\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e32\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35<br \/>\n&#8211; \u0e23\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e31\u0e19\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34<br \/>\n&#8211; \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2d\u0e19\u0e38\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e19\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07<\/h2>\n<h2><strong>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e0a\u0e2d\u0e34\u0e2a\u0e23\u0e34\u0e22\u0e32\u0e20\u0e23\u0e13\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a<\/strong><br \/>\n&#8211; \u0e21\u0e2b\u0e32\u0e1b\u0e23\u0e21\u0e32\u0e20\u0e23\u0e13\u0e4c\u0e0a\u0e49\u0e32\u0e07\u0e40\u0e1c\u0e37\u0e2d\u0e01 (\u0e21.\u0e1b.\u0e0a.)<br \/>\n&#8211; \u0e21\u0e2b\u0e32\u0e27\u0e0a\u0e34\u0e23\u0e21\u0e07\u0e01\u0e38\u0e0e (\u0e21.\u0e27.\u0e21.)<br \/>\n&#8211; \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e40\u0e2a\u0e23\u0e35\u0e0a\u0e19 (\u0e2a.\u0e23.2) \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48 1<br \/>\n&#8211; \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19 (\u0e0a.\u0e14.)<\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1e\u0e25\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e2d\u0e01 \u0e0a\u0e25\u0e34\u0e15 \u0e1e\u0e38\u0e01\u0e1c\u0e32\u0e2a\u0e38\u0e02 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/pages\/4076"}],"collection":[{"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/comments?post=4076"}],"version-history":[{"count":0,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/pages\/4076\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/media?parent=4076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}