{"id":159784,"date":"2026-08-31T00:00:00","date_gmt":"2026-08-30T17:00:00","guid":{"rendered":"https:\/\/www.pbru.ac.th\/pbru\/news\/159784"},"modified":"2026-08-31T09:06:16","modified_gmt":"2026-08-31T02:06:16","slug":"%f0%9f%97%93%e0%b8%aa%e0%b8%b1%e0%b8%9b%e0%b8%94%e0%b8%b2%e0%b8%ab%e0%b9%8c%e0%b8%99%e0%b8%b5%e0%b9%89-pbru-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%95%e0%b9%89","status":"publish","type":"post","link":"https:\/\/www.pbru.ac.th\/pbru\/news\/159784","title":{"rendered":"\ud83d\uddd3\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e19\u0e35\u0e49 PBRU \u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e1e\u0e35\u0e48\u0e46 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\ud83d\udc9a\ud83d\udc9b \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21 \u0e1e\u0e34\u0e18\u0e35\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\ud83d\udc69\u200d\ud83c\udf93"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"159784\" class=\"elementor elementor-159784 elementor-bc-flex-widget\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-558c51f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"558c51f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af1c4e3\" data-id=\"af1c4e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b662507 elementor-widget elementor-widget-text-editor\" data-id=\"b662507\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<div class=\"pbru-card\"><div class=\"pbru-source-bar\"><a href=\"https:\/\/www.facebook.com\/1970577149918528\/posts\/1504838228352957\" target=\"_blank\" rel=\"noopener\" class=\"pbru-source-left\"><svg class=\"pbru-fb-icon\" viewBox=\"0 0 24 24\" fill=\"#1877F2\"><path d=\"M24 12.073c0-6.627-5.373-12-12-12s-12 5.373-12 12c0 5.99 4.388 10.954 10.125 11.854v-8.385H7.078v-3.47h3.047V9.43c0-3.007 1.792-4.669 4.533-4.669 1.312 0 2.686.235 2.686.235v2.953H15.83c-1.491 0-1.956.925-1.956 1.874v2.25h3.328l-.532 3.47h-2.796v8.385C19.612 23.027 24 18.062 24 12.073z\"\/><\/svg><span class=\"pbru-source-label\">Facebook<\/span><\/a><div class=\"pbru-source-right\"><svg class=\"pbru-cal-icon\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><rect x=\"3\" y=\"4\" width=\"18\" height=\"18\" rx=\"2\" ry=\"2\"\/><line x1=\"16\" y1=\"2\" x2=\"16\" y2=\"6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"6\"\/><line x1=\"3\" y1=\"10\" x2=\"21\" y2=\"10\"\/><\/svg><span class=\"pbru-post-date\">31 \u0e2a.\u0e04. 2569 \u0e40\u0e27\u0e25\u0e32 00:00 \u0e19.<\/span><\/div><\/div><div class=\"pbru-news-wrapper\"><h2 class='pbru-headline'>\ud83d\uddd3\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e19\u0e35\u0e49 PBRU \u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e1e\u0e35\u0e48\u0e46 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\ud83d\udc9a\ud83d\udc9b<\/h2><p>\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21 \u0e1e\u0e34\u0e18\u0e35\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\ud83d\udc69\u200d\ud83c\udf93<\/p><p>\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01.\u0e22.69 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21<\/p><p>\u0e40\u0e1e\u0e35\u0e22\u0e07 2 \u0e27\u0e31\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e25\u0e14\u0e25\u0e07\u0e08\u0e32\u0e01\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19 \u0e46 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e49\u0e2d\u0e21\u0e22\u0e48\u0e2d\u0e22 1 \u0e27\u0e31\u0e19<\/p><p>\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48 1 \u0e27\u0e31\u0e19\ud83c\udf89<\/p><p>\ud83d\ude18\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e07\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19 \u0e2a.-\u0e2d.\u0e19\u0e35\u0e49<\/p><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c33cd3c elementor-widget elementor-widget-html\" data-id=\"c33cd3c\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"pbru-hero-image\"><a href=\"https:\/\/www.pbru.ac.th\/pbru\/wp-content\/uploads\/2026\/08\/pbru-159784-6a94e19847fa2.jpg\" class=\"pbru-lightbox\" data-gallery=\"post-159784\"><img decoding=\"async\" src=\"https:\/\/www.pbru.ac.th\/pbru\/wp-content\/uploads\/2026\/08\/pbru-159784-6a94e19847fa2.jpg\" alt=\"\ud83d\uddd3\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e19\u0e35\u0e49 PBRU \u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e1e\u0e35\u0e48\u0e46 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\ud83d\udc9a\ud83d\udc9b \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21 \u0e1e\u0e34\u0e18\u0e35\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\ud83d\udc69\u200d\ud83c\udf93\" loading=\"lazy\" \/><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Facebook 31 \u0e2a.\u0e04. 2569 \u0e40\u0e27\u0e25\u0e32 00:00 \u0e19. \ud83d\uddd3\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e19\u0e35\u0e49 PBRU \u0e40\u0e1b [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":159785,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/posts\/159784"}],"collection":[{"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/comments?post=159784"}],"version-history":[{"count":1,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/posts\/159784\/revisions"}],"predecessor-version":[{"id":159786,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/posts\/159784\/revisions\/159786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/media\/159785"}],"wp:attachment":[{"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/media?parent=159784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/categories?post=159784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pbru.ac.th\/pbru\/wp-json\/wp\/v2\/tags?post=159784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}